{"id":503,"date":"2022-08-12T13:29:39","date_gmt":"2022-08-12T13:29:39","guid":{"rendered":"https:\/\/seligra.com.br\/google\/?p=503"},"modified":"2022-09-01T21:30:24","modified_gmt":"2022-09-01T21:30:24","slug":"niveis-de-consciencia-de-uma-compra-no-google-ads","status":"publish","type":"post","link":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/","title":{"rendered":"N\u00edveis de consci\u00eancia de uma compra no Google ADS"},"content":{"rendered":"\n<p>Convido voc\u00ea a entender mais sobre n\u00edveis de consci\u00eancia de compra no Google ADS. Aperte play.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"nv-iframe-embed\"><iframe title=\"N\u00cdVEIS DE CONSCI\u00caNCIA MOMENTO DE COMPRA YT\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/CP_tXlZPUCY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p>Sempre falo que o Google n\u00e3o vende nada, ele apenas leva a pessoa at\u00e9 voc\u00ea.<\/p>\n\n\n\n<p>Se voc\u00ea n\u00e3o entender os n\u00edveis de consci\u00eancia do processo de vendas n\u00e3o vai aprender o que vende e o que n\u00e3o vende.<\/p>\n\n\n\n<p>Pra isso nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00 em an\u00fancios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/09\/niveis-de-consciencia-de-compra.jpg\" alt=\"n\u00edveis de consci\u00eancia de compra no google ads\n\" class=\"wp-image-582\" width=\"509\" height=\"365\" srcset=\"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/09\/niveis-de-consciencia-de-compra.jpg 800w, https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/09\/niveis-de-consciencia-de-compra-300x215.jpg 300w, https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/09\/niveis-de-consciencia-de-compra-768x551.jpg 768w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/figure>\n\n\n\n<p>Se quiser aprender mais sobre <a href=\"https:\/\/seligra.com.br\/google\/curso-seligra-google-ads-para-empreendedores\/\">como anunciar no Google ADS<\/a> clique no link e conhe\u00e7a meu curso.<\/p>\n\n\n\n<p>E n\u00e3o se esquece de se inscrever l\u00e1 no\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC1E8elb3K5JtHh5C07f_3HA\" target=\"_blank\" rel=\"noreferrer noopener\">meu canal do YouTube F\u00e1bio Seligra Ads<\/a><\/p>\n\n\n\n<p><\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_503\" class=\"pvc_stats all  \" data-element-id=\"503\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/seligra.com.br\/google\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Convido voc\u00ea a entender mais sobre n\u00edveis de consci\u00eancia de compra no Google ADS. Aperte play. Sempre falo que o Google n\u00e3o vende nada, ele apenas leva a pessoa at\u00e9 voc\u00ea. Se voc\u00ea n\u00e3o entender os n\u00edveis de consci\u00eancia do processo de vendas n\u00e3o vai aprender o que vende e o que n\u00e3o vende. Pra&hellip;&nbsp;<a href=\"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/\" rel=\"bookmark\">Ler mais &raquo;<span class=\"screen-reader-text\">N\u00edveis de consci\u00eancia de uma compra no Google ADS<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_503\" class=\"pvc_stats all  \" data-element-id=\"503\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/seligra.com.br\/google\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_joinchat":[],"footnotes":""},"categories":[1],"tags":[36,37,31,35,34,68],"class_list":["post-503","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-google-ads","tag-como-anunciar-no-google-ads","tag-curso-google-ads","tag-google-ads","tag-google-ads-niveis-de-consciencia","tag-google-ads-para-empresas","tag-niveis-de-consciencia-de-compra-no-google","post_format-post-format-video"],"a3_pvc":{"activated":true,"total_views":67,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00edveis de consci\u00eancia de uma compra no Google ADS - F\u00e1bio SELIGRA<\/title>\n<meta name=\"description\" content=\"N\u00edveis de consci\u00eancia de uma compra no Google ADS, nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00edveis de consci\u00eancia de uma compra no Google ADS - F\u00e1bio SELIGRA\" \/>\n<meta property=\"og:description\" content=\"N\u00edveis de consci\u00eancia de uma compra no Google ADS, nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00e1bio SELIGRA\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-12T13:29:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-01T21:30:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/08\/niveis-de-consciencia-de-compra-no-google-ads.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"formato8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"formato8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/\"},\"author\":{\"name\":\"formato8\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/#\\\/schema\\\/person\\\/349deb3d75985d1c7f92ffcc03cce0ea\"},\"headline\":\"N\u00edveis de consci\u00eancia de uma compra no Google ADS\",\"datePublished\":\"2022-08-12T13:29:39+00:00\",\"dateModified\":\"2022-09-01T21:30:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/\"},\"wordCount\":136,\"image\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/niveis-de-consciencia-de-compra-no-google-ads.jpg\",\"keywords\":[\"como anunciar no google ads\",\"curso google ads\",\"Google ads\",\"google ads niveis de consciencia\",\"google ads para empresas\",\"n\u00edveis de consci\u00eancia de compra no google\"],\"articleSection\":[\"Google ADS\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/\",\"url\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/\",\"name\":\"N\u00edveis de consci\u00eancia de uma compra no Google ADS - F\u00e1bio SELIGRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/niveis-de-consciencia-de-compra-no-google-ads.jpg\",\"datePublished\":\"2022-08-12T13:29:39+00:00\",\"dateModified\":\"2022-09-01T21:30:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/#\\\/schema\\\/person\\\/349deb3d75985d1c7f92ffcc03cce0ea\"},\"description\":\"N\u00edveis de consci\u00eancia de uma compra no Google ADS, nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/niveis-de-consciencia-de-compra-no-google-ads.jpg\",\"contentUrl\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/niveis-de-consciencia-de-compra-no-google-ads.jpg\",\"width\":800,\"height\":574,\"caption\":\"n\u00edveis de consci\u00eancia de compra no google\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/niveis-de-consciencia-de-uma-compra-no-google-ads\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00edveis de consci\u00eancia de uma compra no Google ADS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/#website\",\"url\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/\",\"name\":\"F\u00e1bio SELIGRA\",\"description\":\"Google ADS e Google SEO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/#\\\/schema\\\/person\\\/349deb3d75985d1c7f92ffcc03cce0ea\",\"name\":\"formato8\",\"sameAs\":[\"https:\\\/\\\/seligra.com.br\\\/google\"],\"url\":\"https:\\\/\\\/seligra.com.br\\\/google\\\/author\\\/formato8\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00edveis de consci\u00eancia de uma compra no Google ADS - F\u00e1bio SELIGRA","description":"N\u00edveis de consci\u00eancia de uma compra no Google ADS, nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/","og_locale":"pt_PT","og_type":"article","og_title":"N\u00edveis de consci\u00eancia de uma compra no Google ADS - F\u00e1bio SELIGRA","og_description":"N\u00edveis de consci\u00eancia de uma compra no Google ADS, nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00","og_url":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/","og_site_name":"F\u00e1bio SELIGRA","article_published_time":"2022-08-12T13:29:39+00:00","article_modified_time":"2022-09-01T21:30:24+00:00","og_image":[{"width":800,"height":574,"url":"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/08\/niveis-de-consciencia-de-compra-no-google-ads.jpg","type":"image\/jpeg"}],"author":"formato8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"formato8","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#article","isPartOf":{"@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/"},"author":{"name":"formato8","@id":"https:\/\/seligra.com.br\/google\/#\/schema\/person\/349deb3d75985d1c7f92ffcc03cce0ea"},"headline":"N\u00edveis de consci\u00eancia de uma compra no Google ADS","datePublished":"2022-08-12T13:29:39+00:00","dateModified":"2022-09-01T21:30:24+00:00","mainEntityOfPage":{"@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/"},"wordCount":136,"image":{"@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#primaryimage"},"thumbnailUrl":"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/08\/niveis-de-consciencia-de-compra-no-google-ads.jpg","keywords":["como anunciar no google ads","curso google ads","Google ads","google ads niveis de consciencia","google ads para empresas","n\u00edveis de consci\u00eancia de compra no google"],"articleSection":["Google ADS"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/","url":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/","name":"N\u00edveis de consci\u00eancia de uma compra no Google ADS - F\u00e1bio SELIGRA","isPartOf":{"@id":"https:\/\/seligra.com.br\/google\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#primaryimage"},"image":{"@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#primaryimage"},"thumbnailUrl":"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/08\/niveis-de-consciencia-de-compra-no-google-ads.jpg","datePublished":"2022-08-12T13:29:39+00:00","dateModified":"2022-09-01T21:30:24+00:00","author":{"@id":"https:\/\/seligra.com.br\/google\/#\/schema\/person\/349deb3d75985d1c7f92ffcc03cce0ea"},"description":"N\u00edveis de consci\u00eancia de uma compra no Google ADS, nesse v\u00eddeo acima eu mostro uma de minhas contas que fiz mais de 12 mil reais com 450,00","breadcrumb":{"@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#primaryimage","url":"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/08\/niveis-de-consciencia-de-compra-no-google-ads.jpg","contentUrl":"https:\/\/seligra.com.br\/google\/wp-content\/uploads\/2022\/08\/niveis-de-consciencia-de-compra-no-google-ads.jpg","width":800,"height":574,"caption":"n\u00edveis de consci\u00eancia de compra no google"},{"@type":"BreadcrumbList","@id":"https:\/\/seligra.com.br\/google\/niveis-de-consciencia-de-uma-compra-no-google-ads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/seligra.com.br\/google\/"},{"@type":"ListItem","position":2,"name":"N\u00edveis de consci\u00eancia de uma compra no Google ADS"}]},{"@type":"WebSite","@id":"https:\/\/seligra.com.br\/google\/#website","url":"https:\/\/seligra.com.br\/google\/","name":"F\u00e1bio SELIGRA","description":"Google ADS e Google SEO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seligra.com.br\/google\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/seligra.com.br\/google\/#\/schema\/person\/349deb3d75985d1c7f92ffcc03cce0ea","name":"formato8","sameAs":["https:\/\/seligra.com.br\/google"],"url":"https:\/\/seligra.com.br\/google\/author\/formato8\/"}]}},"_links":{"self":[{"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/posts\/503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/comments?post=503"}],"version-history":[{"count":2,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/posts\/503\/revisions"}],"predecessor-version":[{"id":583,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/posts\/503\/revisions\/583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/media\/504"}],"wp:attachment":[{"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/media?parent=503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/categories?post=503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seligra.com.br\/google\/wp-json\/wp\/v2\/tags?post=503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}